{"id":447844,"date":"2023-02-10T00:49:42","date_gmt":"2023-02-10T00:49:42","guid":{"rendered":"https:\/\/www.queermenow.net\/blog\/?p=447844"},"modified":"2023-02-10T10:01:38","modified_gmt":"2023-02-10T10:01:38","slug":"gay-porn-loc-rios-ares-jose-hartman-kristen-bjorn","status":"publish","type":"post","link":"https:\/\/www.queermenow.net\/blog\/gay-porn-loc-rios-ares-jose-hartman-kristen-bjorn\/","title":{"rendered":"Gay Porn Behind The Scenes: Loc Rios, Ares &#038; Jose Hartman 3-Way Fuck Fest On The Set Of Kristen Bjorn"},"content":{"rendered":"<p><a href=\"http:\/\/refer.ccbill.com\/cgi-bin\/clicks.cgi?CA=934718-0000&#038;PA=1563230&#038;HTML=https:\/\/www.kristenbjorn.com\/video-2372\/casting-couch-483-jose-hartman-loc-rios-ares\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn.jpg\" alt=\"Gay Porn Jose Hartman Loc Rios Ares KristenBjorn\" width=\"700\" height=\"529\" class=\"alignnone size-full wp-image-447930\" srcset=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn.jpg 700w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-300x227.jpg 300w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-212x160.jpg 212w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-198x150.jpg 198w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-560x423.jpg 560w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>I think <a href=\"https:\/\/www.queermenow.net\/blog\/tag\/loc-rios\/\">Loc Rios<\/a> is among the luckiest tops in porn. He got to fuck big-dicked top gay porn stars like <a href=\"https:\/\/www.queermenow.net\/blog\/rhyheim-shabazz-bottom-gay-porn-loc-rios\/\">Rhyheim Shabazz<\/a> and <a href=\"https:\/\/www.queermenow.net\/blog\/sean-xavier-double-penetration-gay-porn\/\">Sean Xavier<\/a> (in Sean&#8217;s DP debut!). He just made his Kristen Bjorn debut along with newcomer <strong>Jose Hartman<\/strong> in a bareback 3-way with <a href=\"https:\/\/www.queermenow.net\/blog\/tag\/ares\/\">Ares<\/a>. Be sure to check out Queer Me Now&#8217;s behind the scenes video of this scene where <a href=\"http:\/\/refer.ccbill.com\/cgi-bin\/clicks.cgi?CA=934718-0000&#038;PA=1563230&#038;HTML=https:\/\/www.kristenbjorn.com\/video-2372\/casting-couch-483-jose-hartman-loc-rios-ares\">Ares and Jose Hartman take turns bottoming in a threesome with Loc Rios<\/a>.<\/p>\n<p>[<a href=\"http:\/\/www.kristenbjorn.com\/kbhomeqmn\/en\/1563230\">USE THIS LINK<\/a><strong>]<\/strong> to get <strong>40% OFF<\/strong> Kristen Bjorn membership.<\/p>\n<p><!--more--><\/p>\n<p><div id=\"wpfp_7e90c29bd85ed87534f91130d47a3b15\" data-item=\"{&quot;sources&quot;:[{&quot;src&quot;:&quot;https:\\\/\\\/www.queermenow.net\\\/streamingvideos2\\\/JoseHartmanLocRiosAres-bts.mp4&quot;,&quot;type&quot;:&quot;video\\\/mp4&quot;}],&quot;splash&quot;:&quot;https:\\\/\\\/www.queermenow.net\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-BTS.jpg&quot;}\" class=\"flowplayer no-brand is-splash is-paused skin-slim no-svg fp-slim fp-edgy\" data-fv-embed=\"https:\/\/www.queermenow.net\/blog\/gay-porn-loc-rios-ares-jose-hartman-kristen-bjorn\/fvp\/\" style=\"position:relative; max-width: 700px; max-height: 394px; \" data-ratio=\"0.5629\">\n\t<div class=\"fp-ratio\" style=\"padding-top: 56.29%\"><\/div>\n\t<img decoding=\"async\" class=\"fp-splash\" alt=\"video\" src=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-BTS.jpg\" style=\"position:absolute;top:0;width:100%\" \/>\n\t<div class=\"fp-ui\"><noscript>Please enable JavaScript<\/noscript><div class=\"fp-play fp-visible\"><svg class=\"fp-play-sharp-fill\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 100 100\"><defs><style>.fp-color-play{opacity:0.65;}.controlbutton{fill:#fff;}<\/style><\/defs><title>play-sharp-fill<\/title><path class=\"fp-color-play\" d=\"M49.9217-.078a50,50,0,1,0,50,50A50.0564,50.0564,0,0,0,49.9217-.078Z\"\/><polygon class=\"controlbutton\" points=\"73.601 50 37.968 70.573 37.968 29.427 73.601 50\" filter=\"url(#f1)\"\/><\/svg><\/div><div class=\"fp-preload\"><b><\/b><b><\/b><b><\/b><b><\/b><\/div><\/div>\n<div class='fvp-share-bar'><div><a class=\"sharing-link\" href=\"https:\/\/www.queermenow.net\/blog\/gay-porn-loc-rios-ares-jose-hartman-kristen-bjorn\/\" target=\"_blank\">Link<\/a><\/div><div><label><a class=\"embed-code-toggle\" href=\"#\"><strong>Embed<\/strong><\/a><\/label><\/div><div class=\"embed-code\"><label>Copy and paste this HTML code into your webpage to embed.<\/label><textarea><\/textarea><\/div><\/div>\n<\/div>\n<center><em>Jose Hartman, Loc Rios &#038; Ares On The Set Of Kristen Bjorn<\/em><\/center><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/refer.ccbill.com\/cgi-bin\/clicks.cgi?CA=934718-0000&#038;PA=1563230&#038;HTML=https:\/\/www.kristenbjorn.com\/video-2372\/casting-couch-483-jose-hartman-loc-rios-ares\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-1.jpg\" alt=\"Gay Porn Jose Hartman Loc Rios Ares KristenBjorn \" width=\"700\" height=\"959\" class=\"alignnone size-full wp-image-447937\" srcset=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-1.jpg 700w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-1-219x300.jpg 219w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-1-117x160.jpg 117w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-1-109x150.jpg 109w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-1-560x767.jpg 560w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-2.jpg\" alt=\"Gay Porn Jose Hartman Loc Rios Ares KristenBjorn \" width=\"700\" height=\"378\" class=\"alignnone size-full wp-image-447938\" srcset=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-2.jpg 700w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-2-300x162.jpg 300w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-2-260x140.jpg 260w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-2-200x108.jpg 200w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-2-560x302.jpg 560w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-3.jpg\" alt=\"Gay Porn Jose Hartman Loc Rios Ares KristenBjorn \" width=\"700\" height=\"394\" class=\"alignnone size-full wp-image-447939\" srcset=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-3.jpg 700w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-3-300x169.jpg 300w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-3-260x146.jpg 260w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-3-200x113.jpg 200w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-3-560x315.jpg 560w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-4.jpg\" alt=\"Gay Porn Jose Hartman Loc Rios Ares KristenBjorn \" width=\"700\" height=\"394\" class=\"alignnone size-full wp-image-447940\" srcset=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-4.jpg 700w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-4-300x169.jpg 300w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-4-260x146.jpg 260w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-4-200x113.jpg 200w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-4-560x315.jpg 560w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-5.jpg\" alt=\"Gay Porn Jose Hartman Loc Rios Ares KristenBjorn \" width=\"700\" height=\"394\" class=\"alignnone size-full wp-image-447941\" srcset=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-5.jpg 700w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-5-300x169.jpg 300w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-5-260x146.jpg 260w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-5-200x113.jpg 200w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-5-560x315.jpg 560w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-6.jpg\" alt=\"Gay Porn Jose Hartman Loc Rios Ares KristenBjorn \" width=\"700\" height=\"394\" class=\"alignnone size-full wp-image-447942\" srcset=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-6.jpg 700w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-6-300x169.jpg 300w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-6-260x146.jpg 260w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-6-200x113.jpg 200w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-6-560x315.jpg 560w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-7.jpg\" alt=\"Gay Porn Jose Hartman Loc Rios Ares KristenBjorn \" width=\"700\" height=\"394\" class=\"alignnone size-full wp-image-447943\" srcset=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-7.jpg 700w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-7-300x169.jpg 300w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-7-260x146.jpg 260w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-7-200x113.jpg 200w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-7-560x315.jpg 560w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-8.jpg\" alt=\"Gay Porn Jose Hartman Loc Rios Ares KristenBjorn \" width=\"700\" height=\"403\" class=\"alignnone size-full wp-image-447944\" srcset=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-8.jpg 700w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-8-300x173.jpg 300w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-8-260x150.jpg 260w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-8-200x115.jpg 200w, https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-8-560x322.jpg 560w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<div id=\"wpfp_37d2cad8d6dd60145370deabd4a35957\" data-item=\"{&quot;sources&quot;:[{&quot;src&quot;:&quot;https:\\\/\\\/www.queermenow.net\\\/streamingvideos2\\\/cc483_preview.mp4&quot;,&quot;type&quot;:&quot;video\\\/mp4&quot;}],&quot;splash&quot;:&quot;https:\\\/\\\/www.queermenow.net\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-9.jpg&quot;}\" class=\"flowplayer no-brand is-splash is-paused skin-slim no-svg fp-slim fp-edgy\" data-fv-embed=\"https:\/\/www.queermenow.net\/blog\/gay-porn-loc-rios-ares-jose-hartman-kristen-bjorn\/fvp2\/\" style=\"position:relative; max-width: 700px; max-height: 394px; \" data-ratio=\"0.5629\">\n\t<div class=\"fp-ratio\" style=\"padding-top: 56.29%\"><\/div>\n\t<img decoding=\"async\" class=\"fp-splash\" alt=\"video\" src=\"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-9.jpg\" style=\"position:absolute;top:0;width:100%\" \/>\n\t<div class=\"fp-ui\"><noscript>Please enable JavaScript<\/noscript><div class=\"fp-play fp-visible\"><svg class=\"fp-play-sharp-fill\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 100 100\"><defs><style>.fp-color-play{opacity:0.65;}.controlbutton{fill:#fff;}<\/style><\/defs><title>play-sharp-fill<\/title><path class=\"fp-color-play\" d=\"M49.9217-.078a50,50,0,1,0,50,50A50.0564,50.0564,0,0,0,49.9217-.078Z\"\/><polygon class=\"controlbutton\" points=\"73.601 50 37.968 70.573 37.968 29.427 73.601 50\" filter=\"url(#f1)\"\/><\/svg><\/div><div class=\"fp-preload\"><b><\/b><b><\/b><b><\/b><b><\/b><\/div><\/div>\n<div class='fvp-share-bar'><div><a class=\"sharing-link\" href=\"https:\/\/www.queermenow.net\/blog\/gay-porn-loc-rios-ares-jose-hartman-kristen-bjorn\/\" target=\"_blank\">Link<\/a><\/div><div><label><a class=\"embed-code-toggle\" href=\"#\"><strong>Embed<\/strong><\/a><\/label><\/div><div class=\"embed-code\"><label>Copy and paste this HTML code into your webpage to embed.<\/label><textarea><\/textarea><\/div><\/div>\n<\/div>\n\n<p>[<a href=\"http:\/\/www.kristenbjorn.com\/kbhomeqmn\/en\/1563230\">USE THIS LINK<\/a><strong>]<\/strong> to get <strong>40% OFF<\/strong> Kristen Bjorn membership.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I think Loc Rios is among the luckiest tops in porn. He got to fuck big-dicked top gay porn stars like Rhyheim Shabazz and Sean Xavier (in Sean&rsquo;s DP debut!). He just made his Kristen Bjorn debut along with newcomer Jose Hartman in a bareback 3-way with Ares. Be sure to check out Queer Me [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":447931,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[41],"tags":[7509,99,5,7522,74,7258,597],"class_list":{"0":"post-447844","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-paysite-spotlight","8":"tag-ares","9":"tag-bareback","10":"tag-behind-the-scenes","11":"tag-jose-hartman","12":"tag-kristen-bjorn","13":"tag-loc-rios","14":"tag-newcomer-alert","15":"entry"},"acf":[],"featured_image_src":"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-XXX-600x400.jpg","featured_image_src_square":"https:\/\/www.queermenow.net\/blog\/wp-content\/uploads\/2023\/02\/Gay-Porn-Jose-Hartman-Loc-Rios-Ares-KristenBjorn-XXX-600x500.jpg","author_info":{"display_name":"QMN","author_link":"https:\/\/www.queermenow.net\/blog\/author\/qmn\/"},"_links":{"self":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/posts\/447844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/comments?post=447844"}],"version-history":[{"count":5,"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/posts\/447844\/revisions"}],"predecessor-version":[{"id":447948,"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/posts\/447844\/revisions\/447948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/media\/447931"}],"wp:attachment":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/media?parent=447844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/categories?post=447844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/tags?post=447844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}