{"id":1177,"count":27,"description":"","link":"https:\/\/www.queermenow.net\/blog\/tag\/curtis-sean-cody\/","name":"Curtis (Sean Cody)","slug":"curtis-sean-cody","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/tags\/1177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/posts?tags=1177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}