{"id":3416,"count":30,"description":"","link":"https:\/\/www.queermenow.net\/blog\/tag\/rod-peterson\/","name":"Rod Peterson","slug":"rod-peterson","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/tags\/3416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/posts?tags=3416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}