{"id":4527,"count":2,"description":"","link":"https:\/\/www.queermenow.net\/blog\/tag\/mateo-sanchez\/","name":"Mateo Sanchez","slug":"mateo-sanchez","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/tags\/4527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/posts?tags=4527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}