{"id":462,"count":6,"description":"","link":"https:\/\/www.queermenow.net\/blog\/tag\/tommyd\/","name":"TommyD","slug":"tommyd","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/tags\/462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/posts?tags=462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}