{"id":6470,"count":1,"description":"","link":"https:\/\/www.queermenow.net\/blog\/tag\/trent-cougar\/","name":"Trent Cougar","slug":"trent-cougar","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/tags\/6470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.queermenow.net\/blog\/wp-json\/wp\/v2\/posts?tags=6470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}